{"id":108415,"date":"2026-05-13T09:41:05","date_gmt":"2026-05-13T12:41:05","guid":{"rendered":"https:\/\/fueluniverse.tv\/blog\/?p=108415"},"modified":"2026-05-13T09:41:07","modified_gmt":"2026-05-13T12:41:07","slug":"honda-y-yamaha-anunciaron-sus-equipos-para-las-8-horas-de-suzuka","status":"publish","type":"post","link":"https:\/\/fueluniverse.tv\/blog\/actualidad\/honda-y-yamaha-anunciaron-sus-equipos-para-las-8-horas-de-suzuka\/","title":{"rendered":"Honda y Yamaha anunciaron sus equipos para las 8 Horas de Suzuka"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"770\" height=\"513\" src=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Honda-8-horas-Suzuka-770x513.jpg\" alt=\"\" class=\"wp-image-108416\" srcset=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Honda-8-horas-Suzuka-770x513.jpg 770w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Honda-8-horas-Suzuka-480x320.jpg 480w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Honda-8-horas-Suzuka-768x512.jpg 768w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Honda-8-horas-Suzuka-1536x1024.jpg 1536w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Honda-8-horas-Suzuka.jpg 2048w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><figcaption class=\"wp-element-caption\">Ewc-Suzuka-8-H-2025-Race-Honda HRC,Takumi TAKAHASHI,Johann ZARCO<\/figcaption><\/figure>\n\n\n\n<p>Las dos casas m\u00e1s importantes de Jap\u00f3n quieren ser protagonistas en las tradicionales 8 horas de Suzuka para la 2\u00aa Fecha del Mundial de Resistencia del pr\u00f3ximo 5 y 6 de junio.<\/p>\n\n\n\n<p>Honda confirm\u00f3 a sus pilotos del equipo oficial Honda HRC que competir\u00e1 en el Campeonato Mundial de Resistencia FIM 2026 \u00abCoca-Cola\u00bb Suzuka 8 Horas de Resistencia. HRC aspira a su quinta victoria consecutiva con una alineaci\u00f3n de tres pilotos: Takumi Takahashi, Johann Zarco, piloto del Mundial de MotoGP; y Jonathan Rea, quien actualmente es piloto de pruebas para Honda HRC en el Campeonato Mundial de Superbike FIM (WorldSBK).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"770\" height=\"513\" src=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Zarco-Suzuka-770x513.jpg\" alt=\"\" class=\"wp-image-108418\" srcset=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Zarco-Suzuka-770x513.jpg 770w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Zarco-Suzuka-480x320.jpg 480w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Zarco-Suzuka-768x512.jpg 768w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Zarco-Suzuka-1536x1024.jpg 1536w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Zarco-Suzuka.jpg 2048w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/figure>\n\n\n\n<p>Takahashi logr\u00f3 su cuarta victoria consecutiva en las 8 Horas de Suzuka en 2025, ampliando su r\u00e9cord de m\u00e1s victorias por un solo piloto a siete. Ahora vuelve a liderar el equipo con Zarco, del CASTROL Honda LCR de MotoGP, y el s\u00e9xtuple campe\u00f3n del mundo de Superbike, Jonathan Rea quien regresa a esta ic\u00f3nica carrera de resistencia por primera vez desde 2022 y en busca de su tercera victoria general.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"770\" height=\"514\" src=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Locatelli-770x514.jpg\" alt=\"\" class=\"wp-image-108417\" srcset=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Locatelli-770x514.jpg 770w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Locatelli-480x320.jpg 480w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Locatelli-768x512.jpg 768w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Locatelli-1536x1025.jpg 1536w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Locatelli.jpg 2048w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/figure>\n\n\n\n<p>Yamaha Motor Co. anunci\u00f3 a Jack Miller y Andrea Locatelli en el equipo Yamaha Factory Racing Team para la 47\u00aa edici\u00f3n de las 8 horas de Suzuka 8. Ambos pilotos estar\u00e1n junto a Katsuyuki Nakasuga, sobre la YZF-R1 oficial, el equipo lucir\u00e1 el tradicional #21 de Yamaha mientras aspiran a su novena victoria, la primera de la marca desde 2018.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"770\" height=\"514\" src=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Jack-Miller-770x514.jpg\" alt=\"\" class=\"wp-image-108419\" srcset=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Jack-Miller-770x514.jpg 770w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Jack-Miller-480x320.jpg 480w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Jack-Miller-768x512.jpg 768w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Jack-Miller-1536x1025.jpg 1536w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2026\/05\/Jack-Miller.jpg 2048w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/figure>\n\n\n\n<p>Como parte de la celebraci\u00f3n del 70\u00ba aniversario de Yamaha Motor el a\u00f1o pasado, el equipo oficial volvi\u00f3 a la carrera por primera vez en seis a\u00f1os (desde 2019), y termin\u00f3 la carrera tras completar 217 vueltas\u2014el mismo n\u00famero que el ganador\u2014para terminar segundo. Inmediatamente despu\u00e9s de la carrera, se tom\u00f3 la decisi\u00f3n de competir en las 8 Horas de Suzuka 2026, lo que provoc\u00f3 una revisi\u00f3n exhaustiva de la maquinaria del equipo y una amplia gama de m\u00e9tricas de rendimiento.<\/p>\n\n\n\n<p>El otro equipo oficial ser\u00e1 el actual campe\u00f3n y ganador de las 24 horas de Le Mans, el YART Yamaha con el argentino Leandro Tati Mercado presente en busca de una nueva victoria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las dos casas m\u00e1s importantes de Jap\u00f3n quieren ser protagonistas en las tradicionales 8 horas de Suzuka para la 2\u00aa  [+]<\/p>\n","protected":false},"author":10,"featured_media":108416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[29,3836],"tags":[],"class_list":["post-108415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-endurance"],"acf":[],"_links":{"self":[{"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/posts\/108415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/comments?post=108415"}],"version-history":[{"count":1,"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/posts\/108415\/revisions"}],"predecessor-version":[{"id":108420,"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/posts\/108415\/revisions\/108420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/media\/108416"}],"wp:attachment":[{"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/media?parent=108415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/categories?post=108415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/tags?post=108415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}