{"id":51528,"date":"2017-07-12T17:35:57","date_gmt":"2017-07-12T20:35:57","guid":{"rendered":"https:\/\/fueluniverse.tv\/blog\/?p=51528"},"modified":"2017-07-12T17:35:57","modified_gmt":"2017-07-12T20:35:57","slug":"adelanto-2018-yamaha-yz450f","status":"publish","type":"post","link":"https:\/\/fueluniverse.tv\/blog\/actualidad\/adelanto-2018-yamaha-yz450f\/","title":{"rendered":"Adelanto 2018: Yamaha YZ450F"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-51530\" src=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f-770x512.jpg\" alt=\"\" width=\"770\" height=\"512\" srcset=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f-770x512.jpg 770w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f-480x319.jpg 480w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f-768x511.jpg 768w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f.jpg 840w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<p>El t\u00e9rmino \u201ccompletamente nuevo\u201d es muchas veces utilizado con algo de liviandad, pero este no es el caso de la <strong>YZ450F<\/strong> de Yamaha. A pesar de parecerse a primera vista al modelo 2017, cada pieza de la nueva moto ha sido cambiada o actualizada. El resultado es un chasis radicalmente diferente, un motor de suave funcionamiento que ofrece m\u00e1s potencia que nunca, una carrocer\u00eda m\u00e1s delgada y una electr\u00f3nica diferente a cualquier cosa vista anteriormente.<\/p>\n<p>Lo que m\u00e1s llama la atenci\u00f3n es la electr\u00f3nica. Yamaha present\u00f3 su nueva aplicaci\u00f3n <strong>Power Tuner<\/strong>, que utiliza las mismas capacidades del <strong>GYTR Power Tuner<\/strong>, pero desde un Smartphone, permitiendo cargar los remapeos y modificaciones a la inyecci\u00f3n de combustible y la ignici\u00f3n de manera remota por <strong>Wifi<\/strong>, para lo que la moto cuenta con un receptor de se\u00f1al en la parte trasera. La aplicaci\u00f3n permite guardar los diferentes seteos para ser reutilizados, registra los resultados de distintas carreras y mapas de circuitos. Otra gran caracter\u00edstica de la aplicaci\u00f3n es un registro de mantenimiento que nos indica cuando la maquina podr\u00eda necesitarlo.<\/p>\n<p>Como muchas de las motos nuevas de este segmento, el arranque el\u00e9ctrico es est\u00e1ndar en la YZ450F 2018, junto con una bater\u00eda de litio ultraligera, lo que permite que la YZ termine siendo m\u00e1s liviana que el modelo 2017. Para aquellos m\u00e1s conservadores que todav\u00eda prefieren \u201cpatear\u201d la moto, Yamaha ofrecer\u00e1 un kickstarter como opcional.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-51532\" src=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f3-770x512.jpg\" alt=\"\" width=\"770\" height=\"512\" srcset=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f3-770x512.jpg 770w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f3-480x319.jpg 480w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f3-768x511.jpg 768w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f3.jpg 840w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<p>Yamaha tambi\u00e9n cambio el motor, basado en el de la YZ450F 2017, no s\u00f3lo para lograr m\u00e1s potencia, sino tambi\u00e9n para lograr una moto m\u00e1s f\u00e1cil de controlar. El nuevo motor cuenta con una <strong>cabeza de cilindro, pist\u00f3n, perfiles de leva y geometr\u00eda del cilindro actualizados<\/strong> logrando un funcionamiento m\u00e1s eficiente para 2018. La nueva cabeza del cilindro fue colocada en un \u00e1ngulo ligeramente m\u00e1s vertical para mejorar la distribuci\u00f3n de peso en la parte delantera. En cuanto a la relaci\u00f3n de compresi\u00f3n, fue aumentada hasta <strong>12,8: 1<\/strong>, gracias en parte al nuevo pist\u00f3n de tipo <em><strong>bridge-box<\/strong><\/em>, que es m\u00e1s resistente, pero reduce el material total utilizado. El cambio fue repasado por completo con engranajes redise\u00f1ados para ofrecer una mayor superficie, nuevos discos de embrague, una placa de presi\u00f3n externa m\u00e1s r\u00edgida y una nueva palanca de cambios, que a\u00f1aden durabilidad a la m\u00e1quina. Estos cambios tambi\u00e9n resultan en una <strong>menor masa rotatoria<\/strong>, lo que hace que la moto se sienta m\u00e1s ligera y suave.<\/p>\n<p>El motor es alimentado ahora por un nuevo cuerpo de acelerador <strong>Mikuni de 44 mm<\/strong> con una bomba el\u00e9ctrica de alta presi\u00f3n para asegurar la atomizaci\u00f3n \u00f3ptima del combustible. Este es m\u00e1s compacto y liviano que la unidad anterior e incluso cuenta con una funci\u00f3n de arranque en fr\u00edo que facilita su uso. El filtro y tomas de aire fueron tambi\u00e9n redise\u00f1ados para facilitar el mantenimiento, en tanto que el escape es 12 mm m\u00e1s largo y 3 mm menor en di\u00e1metro que el anterior.<\/p>\n<p>La carrocer\u00eda tambi\u00e9n es nueva y no solo es m\u00e1s liviana, sino que tambi\u00e9n es m\u00e1s estrecha y la altura de asiento es menor, mejorando la maniobrabilidad. Para lograr la carrocer\u00eda m\u00e1s estrecha, los radiadores se colocaron m\u00e1s cerca del chasis y en un \u00e1ngulo m\u00e1s vertical. Adem\u00e1s, los radiadores tienen una mayor capacidad y capturan m\u00e1s flujo de aire, pero son m\u00e1s delgados que los modelos anteriores. Al lograr reducir el tama\u00f1o del asiento, el bastidor y el tanque de combustible, Yamaha logro producir una moto <strong>18 mm m\u00e1s delgada en el cockpit<\/strong>.<\/p>\n<p>Desde el punto de vista est\u00e9tico son bienvenidas las llantas azules, <strong>Team Yamaha Blue<\/strong>, que destacan sobre los habituales negro o plateado. Pero no es solo pinta, son realmente m\u00e1s ligeras gracias a un dise\u00f1o m\u00e1s plano. Montan cubiertas <strong>Dunlop MX3S<\/strong>.<\/p>\n<p>Por \u00faltimo, para 2018 vuelven las suspensiones <strong>Kayaba SSS<\/strong>, con una la configuraci\u00f3n revisada y menor peso total. La Yamaha tambi\u00e9n cuenta con un disco de freno delantero de <strong>270 mm<\/strong>, gu\u00edas ajustables de 4 posiciones con barras de 1 1\/8 \u00ab, reposapi\u00e9s de 55 mm de ancho, un embrague de ajuste r\u00e1pido y gr\u00e1ficos integrados disponibles en el equipo Yamaha Azul o Blanco.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-51533\" src=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f4-770x512.jpg\" alt=\"\" width=\"770\" height=\"512\" srcset=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f4-770x512.jpg 770w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f4-480x319.jpg 480w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f4-768x511.jpg 768w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/yamaha-yz450f4.jpg 840w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<p><strong>Ficha t\u00e9cnica<\/strong><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-51536\" src=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-770x440.png\" alt=\"\" width=\"770\" height=\"440\" srcset=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-770x440.png 770w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-480x274.png 480w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-768x439.png 768w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F.png 973w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-51534\" src=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-2-770x517.png\" alt=\"\" width=\"770\" height=\"517\" srcset=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-2-770x517.png 770w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-2-480x322.png 480w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-2-768x516.png 768w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-2.png 972w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-51535\" src=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-3-770x518.png\" alt=\"\" width=\"770\" height=\"518\" srcset=\"https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-3-770x518.png 770w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-3-480x323.png 480w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-3-768x517.png 768w, https:\/\/fueluniverse.tv\/blog\/wp-content\/uploads\/2017\/07\/YZ450F-3.png 972w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El t\u00e9rmino \u201ccompletamente nuevo\u201d es muchas veces utilizado con algo de liviandad, pero este no es el caso de la  [+]<\/p>\n","protected":false},"author":12,"featured_media":51531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[29],"tags":[27,1450],"class_list":["post-51528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-yamaha","tag-yz450f"],"acf":[],"_links":{"self":[{"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/posts\/51528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/comments?post=51528"}],"version-history":[{"count":0,"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/posts\/51528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/media\/51531"}],"wp:attachment":[{"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/media?parent=51528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/categories?post=51528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fueluniverse.tv\/blog\/wp-json\/wp\/v2\/tags?post=51528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}